{"id":614,"date":"2021-03-09T03:45:35","date_gmt":"2021-03-09T03:45:35","guid":{"rendered":"http:\/\/www.bilingualglobalmentari.sch.id\/?page_id=614"},"modified":"2026-06-17T12:41:27","modified_gmt":"2026-06-17T12:41:27","slug":"kurikulum","status":"publish","type":"page","link":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/kurikulum\/","title":{"rendered":"Kurikulum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"614\" class=\"elementor elementor-614\" data-elementor-settings=\"[]\">\n\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<header class=\"elementor-element elementor-element-04f1990 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"04f1990\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<nav class=\"elementor-element elementor-element-e4678d2 elementor-column elementor-col-20 elementor-top-column\" data-id=\"e4678d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0754ebc elementor-widget elementor-widget-image\" data-id=\"0754ebc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img src=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/elementor\/thumbs\/LogoTK-p39n0cxm1vooqpva9cclwcvif4zuj5mmiuez8wacjo.png\" title=\"LogoTK\" alt=\"LogoTK\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<nav class=\"elementor-element elementor-element-466df74 elementor-column elementor-col-20 elementor-top-column\" data-id=\"466df74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<div class=\"elementor-element elementor-element-e22c6f4 elementor-column elementor-col-20 elementor-top-column\" data-id=\"e22c6f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-782971b elementor-nav-menu__align-center elementor-nav-menu--indicator-chevron elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-invisible elementor-widget elementor-widget-nav-menu\" data-id=\"782971b\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav role=\"navigation\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\"><ul id=\"menu-1-782971b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-622\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/\" class=\"elementor-item\">Beranda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-623\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/kurikulum\/\" class=\"elementor-item\">Kurikulum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-624\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/program-kami\/\" class=\"elementor-item\">Program Kami<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-625\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/fasilitas-pelayanan\/\" class=\"elementor-item\">Fasilitas<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-626\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/pendaftaran\/\" class=\"elementor-item\">Pendaftaran<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i class=\"eicon-menu-bar\" aria-hidden=\"true\"><\/i>\n\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" role=\"navigation\" aria-hidden=\"true\"><ul id=\"menu-2-782971b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-622\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/\" class=\"elementor-item\">Beranda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-623\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/kurikulum\/\" class=\"elementor-item\">Kurikulum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-624\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/program-kami\/\" class=\"elementor-item\">Program Kami<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-625\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/fasilitas-pelayanan\/\" class=\"elementor-item\">Fasilitas<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-626\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/pendaftaran\/\" class=\"elementor-item\">Pendaftaran<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<nav class=\"elementor-element elementor-element-4ab46da elementor-column elementor-col-20 elementor-top-column\" data-id=\"4ab46da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e5a1c7 elementor-widget elementor-widget-image\" data-id=\"0e5a1c7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/profile-kami\/\">\n\t\t\t\t\t\t\t<img src=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/elementor\/thumbs\/ind-p3qd77ipaz02581tsosfrqhta4lkutjutah8cvlnyo.png\" title=\"ind\" alt=\"ind\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<nav class=\"elementor-element elementor-element-60a89c4 elementor-column elementor-col-20 elementor-top-column\" data-id=\"60a89c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6061261 elementor-widget elementor-widget-image\" data-id=\"6061261\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/school-profile\/\">\n\t\t\t\t\t\t\t<img src=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/elementor\/thumbs\/eng-p3qd76kv44yrtm36y6dt78qcoqq7n4g4h5tqvln24w.png\" title=\"eng\" alt=\"eng\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-element elementor-element-22afa42 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"22afa42\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e5a871 elementor-column elementor-col-100 elementor-top-column\" data-id=\"7e5a871\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50a6949 elementor-widget elementor-widget-heading\" data-id=\"50a6949\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/indo\/\"><span style=\"color: #0000ff;\">Beranda<\/span><\/a> &nbsp;\/ Kurikulum Kami <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-621c441 elementor-widget elementor-widget-heading\" data-id=\"621c441\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kurikulum Kami<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8738e6 elementor-widget elementor-widget-spacer\" data-id=\"e8738e6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eabb26 elementor-widget elementor-widget-heading\" data-id=\"3eabb26\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Di sekolah kami, kami menerapkan Permen 58 tahun 2009 yang mencakup 6 program pengembangan, yaitu agama dan moral, kognitif, motorik, sosial emosional, bahasa dan seni. Kami juga mengadopsi pendekatan tematik yang bervariasi sepanjang tahun ajaran seperti: Diri Sendiri, Lingkungan, Hewan, Tanaman, Komunikasi, Transportasi, Luar Angkasa dan sebagainya. <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2aa5ec elementor-widget elementor-widget-heading\" data-id=\"d2aa5ec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kami mengurangi penggunaan buku teks dan menerapkan aktivitas belajar interaktif. Siswa belajar secara dominan melalui membentuk, merasakan, menciptakan dan  berbagai kegiatan belajar aktif lainnya. Strategi pengajaran kami memastikan anak \u2013 anak belajar dengan bermakna, konstekstual dan menantang.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f59548c elementor-widget elementor-widget-toggle\" data-id=\"f59548c\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\" role=\"tablist\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2571\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-2571\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"elementor-toggle-title\">A. Pendekatan Tematik<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2571\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2571\"><p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-918\" src=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20151007_103302-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20151007_103302-300x169.jpg 300w, http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20151007_103302-1024x576.jpg 1024w, http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20151007_103302-768x432.jpg 768w, http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20151007_103302.jpg 1067w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Kami membawakan 11 tema berbeda sepanjang 1 tahun ajaran :<\/p><ul><li>Diri Sendiri<\/li><li>Lingkungan<\/li><li>Kebutuhanku<\/li><li>Hewan<\/li><li>Tanaman<\/li><li>Profesi,\u00a0<\/li><li>Rekreasi<\/li><li>Air \u2013 Api \u2013 Udara<\/li><li>Komunikasi<\/li><li>Tanah Air<\/li><li>Alam Semesta<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2572\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-2572\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"elementor-toggle-title\">B. Metode penilaian<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2572\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2572\"><p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-981\" src=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20160216_091241-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20160216_091241-300x169.jpg 300w, http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20160216_091241-1024x576.jpg 1024w, http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20160216_091241-768x432.jpg 768w, http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20160216_091241.jpg 1067w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Beraneka metode penilaian yang digunakan untuk menilai penanaman siswa akan tema\u00a0 dan materi yang disampaikan di kelas :<\/p><ul><li>Observasi<\/li><li>Catatan Anekdot<\/li><li>Catatan Medis<\/li><li>Wawancara<\/li><li>Portofolio<\/li><li>Unjuk Kerja<\/li><li>Lembar Kerja<\/li><li>dan lain sebagainya.\u00a0<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2573\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-2573\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"elementor-toggle-title\">C. Aktivitas Kelas<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2573\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2573\"><p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-1069\" src=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20200117_103749-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20200117_103749-300x225.jpg 300w, http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20200117_103749-768x576.jpg 768w, http:\/\/www.bilingualglobalmentari.sch.id\/wp-content\/uploads\/2021\/03\/IMG_20200117_103749.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Beragam aktivitas belajar mengajar dijalankan setiap hari.\u00a0<\/p><ul><li><em>Circle Time<\/em><\/li><li>Bercerita<\/li><li>Diskusi<\/li><li>Eksperimen<\/li><li>Presentasi<\/li><li>Lembar kerja<\/li><li>Seni<\/li><li>Memasak<\/li><li>dan lain sebagainya<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-64665b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"64665b3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d98e642 elementor-column elementor-col-100 elementor-top-column\" data-id=\"d98e642\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1516a93 elementor-widget elementor-widget-spacer\" data-id=\"1516a93\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-1f0c966 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"1f0c966\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8048b63 elementor-invisible elementor-column elementor-col-25 elementor-top-column\" data-id=\"8048b63\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;slideInDown&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1655271 elementor-widget elementor-widget-text-editor\" data-id=\"1655271\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><h5 style=\"text-align: center;\">Bilingual Global Mentari<\/h5><p style=\"text-align: center;\">Komp. Villa Indah Pamulang Kav. 7,<br \/>Pd. Petir, Kec. Bojongsari, Kota Depok, Jawa Barat 16517<\/p><p style=\"text-align: center;\"><strong>Telephone :<\/strong> +62812 8360287<br \/><strong>Email :<\/strong> info@bilingualglobalmentari.sch.id<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-961ffa0 elementor-shape-circle elementor-widget elementor-widget-social-icons\" data-id=\"961ffa0\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper\">\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-c21828e\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t<i class=\"fab fa-twitter\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-b9c84a3\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f228f7a\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-skype elementor-repeater-item-f4c2597\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Skype<\/span>\n\t\t\t\t\t<i class=\"fab fa-skype\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-42415c5\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80a6ce0 elementor-column elementor-col-25 elementor-top-column\" data-id=\"80a6ce0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b1c0ad elementor-widget elementor-widget-heading\" data-id=\"7b1c0ad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-small\">Shortcut Menu<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a12918b elementor-nav-menu--indicator-classic elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"a12918b\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav role=\"navigation\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-grow\"><ul id=\"menu-1-a12918b\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-602\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/\" class=\"elementor-item\">Beranda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-611\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/profile-kami\/\" class=\"elementor-item\">Profile Kami<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-613\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/pendaftaran\/\" class=\"elementor-item\">Pendaftaran<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i class=\"eicon-menu-bar\" aria-hidden=\"true\"><\/i>\n\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" role=\"navigation\" aria-hidden=\"true\"><ul id=\"menu-2-a12918b\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-602\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/\" class=\"elementor-item\">Beranda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-611\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/profile-kami\/\" class=\"elementor-item\">Profile Kami<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-613\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/pendaftaran\/\" class=\"elementor-item\">Pendaftaran<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69341f6 elementor-column elementor-col-25 elementor-top-column\" data-id=\"69341f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ede7104 elementor-widget elementor-widget-heading\" data-id=\"ede7104\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-small\">Our Academic<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0188e30 elementor-nav-menu--indicator-classic elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"0188e30\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav role=\"navigation\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-grow\"><ul id=\"menu-1-0188e30\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-627\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/\" class=\"elementor-item\">Beranda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-628\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/kurikulum\/\" class=\"elementor-item\">Kurikulum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-629\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/program-kami\/\" class=\"elementor-item\">Program Kami<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-634\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/kegiatan\/\" class=\"elementor-item\">Galeri<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-635\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/fasilitas-pelayanan\/\" class=\"elementor-item\">Fasilitas<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i class=\"eicon-menu-bar\" aria-hidden=\"true\"><\/i>\n\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" role=\"navigation\" aria-hidden=\"true\"><ul id=\"menu-2-0188e30\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-627\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/\" class=\"elementor-item\">Beranda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-628\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/kurikulum\/\" class=\"elementor-item\">Kurikulum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-629\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/program-kami\/\" class=\"elementor-item\">Program Kami<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-634\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/kegiatan\/\" class=\"elementor-item\">Galeri<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-635\"><a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/fasilitas-pelayanan\/\" class=\"elementor-item\">Fasilitas<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-470b995 elementor-column elementor-col-25 elementor-top-column\" data-id=\"470b995\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd1d5b7 elementor-widget elementor-widget-heading\" data-id=\"fd1d5b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-small\">Registration<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a66efc elementor-align-left elementor-widget elementor-widget-button\" data-id=\"0a66efc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/pendaftaran\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Pendaftaran<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-6ee7a90 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"6ee7a90\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d26a5b elementor-column elementor-col-100 elementor-top-column\" data-id=\"0d26a5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb06ab elementor-widget elementor-widget-spacer\" data-id=\"3bb06ab\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abef473 elementor-widget elementor-widget-heading\" data-id=\"abef473\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a9 Copyright 2021 <strong>Bilingual Global Mentari.<\/strong> All Rights Reserved <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Beranda &nbsp;\/ Kurikulum Kami Kurikulum Kami Di sekolah kami, kami menerapkan Permen 58 tahun 2009 yang mencakup 6 program pengembangan, yaitu agama dan moral, kognitif, motorik, sosial emosional, bahasa dan seni. Kami juga mengadopsi pendekatan tematik yang bervariasi sepanjang tahun ajaran seperti: Diri Sendiri, Lingkungan, Hewan, Tanaman, Komunikasi, Transportasi, Luar Angkasa dan sebagainya. Kami mengurangi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":[],"_links":{"self":[{"href":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/wp-json\/wp\/v2\/pages\/614"}],"collection":[{"href":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/wp-json\/wp\/v2\/comments?post=614"}],"version-history":[{"count":10,"href":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/wp-json\/wp\/v2\/pages\/614\/revisions"}],"predecessor-version":[{"id":1369,"href":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/wp-json\/wp\/v2\/pages\/614\/revisions\/1369"}],"wp:attachment":[{"href":"http:\/\/www.bilingualglobalmentari.sch.id\/index.php\/wp-json\/wp\/v2\/media?parent=614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}